{"id":16497,"date":"2026-02-17T09:40:14","date_gmt":"2026-02-17T09:40:14","guid":{"rendered":"https:\/\/havos.pt\/?page_id=16497"},"modified":"2026-03-12T21:48:50","modified_gmt":"2026-03-12T21:48:50","slug":"jorge-marques-pinto","status":"publish","type":"page","link":"https:\/\/havos.pt\/pt_pt\/havos\/jorge-marques-pinto\/","title":{"rendered":"Jorge Marques Pinto"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"16497\" class=\"elementor elementor-16497\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a8fcdff e-flex e-con-boxed pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-parent \" data-id=\"a8fcdff\" data-element_type=\"container\" data-e-type=\"container\">\t\t\t<div class=\"e-con-inner\">\r\n\t\t<div class=\"elementor-element elementor-element-5f27534 e-con-full e-flex pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"5f27534\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\"><div class=\"elementor-element elementor-element-b61d740 e-con-full pxl-row-divider-active pxl-row-divider-divider-border-line e-flex pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"b61d740\" data-element_type=\"container\" data-e-type=\"container\"><div class=\"pxl-divider-border-line\"><div class=\"pxl-item-line pxl-border-line-top pxl-item-line-width\"><\/div><div class=\"pxl-item-line pxl-border-line-bottom pxl-item-line-width\"><\/div><div class=\"pxl-item-line pxl-border-line-left pxl-item-line-height\"><\/div><div class=\"pxl-item-line pxl-border-line-right pxl-item-line-height\"><\/div><div class=\"pxl-item-line pxl-border-line-top-left pxl-border-corner wow LineRotate\" data-wow-delay=\"300ms\"><\/div><div class=\"pxl-item-line pxl-border-line-top-right pxl-border-corner wow LineRotate\" data-wow-delay=\"300ms\"><\/div><div class=\"pxl-item-line pxl-border-line-bottom-left pxl-border-corner wow LineRotate\" data-wow-delay=\"300ms\"><\/div><div class=\"pxl-item-line pxl-border-line-bottom-right pxl-border-corner wow LineRotate\" data-wow-delay=\"300ms\"><\/div><\/div>\t\t<div class=\"elementor-element elementor-element-5c3a213 elementor-widget elementor-widget-pxl_slider\" data-id=\"5c3a213\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n    <div class=\"pxl-swiper-slider pxl-element-slider pxl-swiper-nogap style1\" >\n        <div class=\"pxl-carousel-inner\">\n            <div class=\"pxl-swiper-container\" dir=\"ltr\" data-settings=\"{&quot;slide_direction&quot;:&quot;horizontal&quot;,&quot;slide_percolumn&quot;:&quot;1&quot;,&quot;slide_mode&quot;:&quot;fade&quot;,&quot;slides_to_show&quot;:&quot;1&quot;,&quot;slides_to_show_xxl&quot;:&quot;1&quot;,&quot;slides_to_show_lg&quot;:&quot;1&quot;,&quot;slides_to_show_md&quot;:&quot;1&quot;,&quot;slides_to_show_sm&quot;:&quot;1&quot;,&quot;slides_to_show_xs&quot;:&quot;1&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;arrow&quot;:false,&quot;pagination&quot;:false,&quot;pagination_type&quot;:&quot;bullets&quot;,&quot;autoplay&quot;:false,&quot;pause_on_hover&quot;:false,&quot;pause_on_interaction&quot;:true,&quot;delay&quot;:5000,&quot;loop&quot;:false,&quot;speed&quot;:500}\">\n                <div class=\"pxl-swiper-wrapper\">\n                                                <div class=\"pxl-swiper-slide\">\n                                <div class=\"pxl-slider--inner elementor-repeater-item-2a9a549\">\n                                                                        <div class=\"pxl-slider--content\">\n                                        \t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"16499\" class=\"elementor elementor-16499\" data-elementor-post-type=\"pxl-template\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4061eaa e-con-full e-flex pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-parent \" data-id=\"4061eaa\" data-element_type=\"container\" data-e-type=\"container\"><div class=\"elementor-element elementor-element-88babba e-con-full e-flex pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"88babba\" data-element_type=\"container\" data-e-type=\"container\">\t\t<div class=\"elementor-element elementor-element-37f7048 elementor-widget elementor-widget-pxl_heading\" data-id=\"37f7048\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div id=\"pxl-pxl_heading-37f7048-3918\" class=\"pxl-heading px-sub-title-default-style \">\n\t<div class=\"pxl-heading--inner\">\n\t\t<div class=\"pxl-heading-content\">\n\t\t\t\n\t\t\t<h1 class=\"pxl-item--title clip style-default highlight-default \" data-wow-delay=\"ms\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\tJorge Marques Pinto\t\n\t\t\t\t\t\n\t\t\t<\/h1>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e104929 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"e104929\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner style-default \" data-wow-delay=\"ms\">\n\t\tSenior Advisor\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t<div class=\"elementor-element elementor-element-db5b659 e-con-full e-flex pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"db5b659\" data-element_type=\"container\" data-e-type=\"container\">\t\t<div class=\"elementor-element elementor-element-ce0bfaa elementor-widget elementor-widget-pxl_banner_box\" data-id=\"ce0bfaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_banner_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-banner-box pxl-banner-box2\">\r\n    <div class=\"pxl-banner-inner\">\r\n        <div class=\"pxl-item-left\">\r\n                                            <\/div>\r\n                    <div class=\"pxl-item--img wow zoomInSmall\" data-wow-delay=\"500ms\">\r\n                <div class=\"pxl-image\">\r\n                    <img fetchpriority=\"high\" decoding=\"async\" class=\"\" src=\"https:\/\/havos.pt\/wp-content\/uploads\/2026\/02\/Jorge-Marques-Pinto-Havos-490x490.png\" width=\"490\" height=\"490\" alt=\"Pessoa em traje formal posa contra parede listrada.\" title=\"Jorge Marques Pinto - Havos\" \/>                <\/div>\r\n            <\/div>\r\n                <div class=\"pxl-item-right\">\r\n                                            <\/div>\r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t<div class=\"elementor-element elementor-element-bcb8d8d e-con-full e-flex pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"bcb8d8d\" data-element_type=\"container\" data-e-type=\"container\">\t\t<div class=\"elementor-element elementor-element-df19716 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"df19716\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner style-default wow fadeInUp\" data-wow-delay=\"700ms\">\n\t\t<p>Consultor s\u00e9nior em desenvolvimento imobili\u00e1rio com d\u00e9cadas de experi\u00eancia em conce\u00e7\u00e3o estrat\u00e9gica de projetos, estrutura\u00e7\u00e3o de investimentos e desenvolvimento imobili\u00e1rio em grande escala. A sua carreira abrange fun\u00e7\u00f5es de lideran\u00e7a em projetos inovadores residenciais, comerciais e tur\u00edsticos, combinando vis\u00e3o conceptual com execu\u00e7\u00e3o em v\u00e1rios ciclos de mercado. Reconhecido por criar conceitos de desenvolvimento diferenciados e contribuir para projetos marcantes, ele traz uma vasta experi\u00eancia em estrat\u00e9gia e consultoria imobili\u00e1ria.<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-114ade7 e-con-full e-flex pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"114ade7\" data-element_type=\"container\" data-e-type=\"container\">\t\t<div class=\"elementor-element elementor-element-4b4ddf9 elementor-widget elementor-widget-pxl_button_custom\" data-id=\"4b4ddf9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_button_custom.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-button-custom pxl-button-custom1 style2\">\r\n    <div class=\"pxl-item--inner pxl-atc-onepage \" data-wow-delay=\"ms\">\r\n        <a class=\"btn-cutom btn\" href=\"#section-team-details\" data-onepage-offset=\"100\">                                        <span class=\"pxl-icon-arrow\">\r\n                    <svg width=\"14\" height=\"7\" viewBox=\"0 0 14 7\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\r\n                      <path d=\"M13 1.5L7 5.5L1 1.5\" stroke=\"white\" stroke-width=\"1.5\" stroke-linejoin=\"round\"\/>\r\n                    <\/svg>\r\n                    <svg width=\"14\" height=\"7\" viewBox=\"0 0 14 7\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\r\n                      <path d=\"M13 1.5L7 5.5L1 1.5\" stroke=\"white\" stroke-width=\"1.5\" stroke-linejoin=\"round\"\/>\r\n                    <\/svg>\r\n                <\/span>\r\n                <span class=\"pxl-btn-title\">Deslize para explorar<\/span>\r\n                    <\/a>    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t                                    <\/div>\n                               <\/div>\n                            <\/div>\n                                                            <\/div>\n            <\/div>\n        <\/div>\n\n        \n        \n    <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t<div class=\"elementor-element elementor-element-d462fcb e-flex e-con-boxed pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-parent \" data-id=\"d462fcb\" data-element_type=\"container\" data-e-type=\"container\">\t\t\t<div class=\"e-con-inner\">\r\n\t\t<div class=\"elementor-element elementor-element-0211a18 e-con-full e-flex pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"0211a18\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\"><div class=\"elementor-element elementor-element-cd06df5 e-con-full pxl-row-scroll-fixed e-flex pxl-column-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"cd06df5\" data-element_type=\"container\" data-e-type=\"container\"><div class=\"elementor-element elementor-element-6738604 e-con-full pxl-column-sticky e-flex pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"6738604\" data-element_type=\"container\" data-e-type=\"container\">\t\t<div class=\"elementor-element elementor-element-5964547 elementor-widget elementor-widget-pxl_heading\" data-id=\"5964547\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div id=\"pxl-pxl_heading-5964547-5903\" class=\"pxl-heading px-sub-title-default-style \">\n\t<div class=\"pxl-heading--inner\">\n\t\t<div class=\"pxl-heading-content\">\n\t\t\t\n\t\t\t<h3 class=\"pxl-item--title clip style-default highlight-default \" data-wow-delay=\"ms\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\tCompet\u00eancias Principais\t\n\t\t\t\t\t\n\t\t\t<\/h3>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1175adf elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-pxl_border_animate\" data-id=\"1175adf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"pxl_border_animate.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-border-animate pxl-border-animate1 default\">\r\n  <div class=\"pxl-border-inner \" data-wow-delay=\"ms\"><\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60df98f elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-pxl_border_animate\" data-id=\"60df98f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"pxl_border_animate.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-border-animate pxl-border-animate1 default\">\r\n  <div class=\"pxl-border-inner \" data-wow-delay=\"ms\"><\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t<div class=\"elementor-element elementor-element-6f11c57 e-con-full e-flex pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"6f11c57\" data-element_type=\"container\" data-e-type=\"container\"><div class=\"elementor-element elementor-element-32c0911 e-con-full e-flex pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"32c0911\" data-element_type=\"container\" data-e-type=\"container\">\t\t<div class=\"elementor-element elementor-element-84a4c87 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"84a4c87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner style-default \" data-wow-delay=\"ms\">\n\t\t<p>1. Estrat\u00e9gia de desenvolvimento imobili\u00e1rio<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ffbabeb elementor-widget elementor-widget-pxl_text_editor\" data-id=\"ffbabeb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner style-default \" data-wow-delay=\"ms\">\n\t\t<p>2. Cria\u00e7\u00e3o de conceitos e posicionamento de projetos<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aef8641 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"aef8641\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner style-default \" data-wow-delay=\"ms\">\n\t\t<p>3. Desenvolvimento residencial e de resorts em grande escala<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9330e1d elementor-widget elementor-widget-pxl_text_editor\" data-id=\"9330e1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner style-default \" data-wow-delay=\"ms\">\n\t\t<p>4. Consultoria de investimento em desenvolvimento imobili\u00e1rio<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f1f54d elementor-widget elementor-widget-pxl_text_editor\" data-id=\"8f1f54d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner style-default \" data-wow-delay=\"ms\">\n\t\t<p>5. Estrat\u00e9gia de comercializa\u00e7\u00e3o e marketing<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25fb3ba elementor-widget elementor-widget-pxl_text_editor\" data-id=\"25fb3ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner style-default \" data-wow-delay=\"ms\">\n\t\t<p>6. Inova\u00e7\u00e3o em design, materiais e segmenta\u00e7\u00e3o de mercado<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t<div class=\"elementor-element elementor-element-4c798fb e-flex e-con-boxed pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-parent \" data-id=\"4c798fb\" data-element_type=\"container\" data-e-type=\"container\">\t\t\t<div class=\"e-con-inner\">\r\n\t\t<div class=\"elementor-element elementor-element-dd0f63b e-con-full e-flex pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"dd0f63b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\"><div class=\"elementor-element elementor-element-c47d480 e-con-full pxl-row-scroll-fixed e-flex pxl-column-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"c47d480\" data-element_type=\"container\" data-e-type=\"container\"><div class=\"elementor-element elementor-element-575cf01 e-con-full pxl-column-sticky e-flex pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"575cf01\" data-element_type=\"container\" data-e-type=\"container\">\t\t<div class=\"elementor-element elementor-element-003804e elementor-widget elementor-widget-pxl_heading\" data-id=\"003804e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div id=\"pxl-pxl_heading-003804e-6862\" class=\"pxl-heading px-sub-title-default-style \">\n\t<div class=\"pxl-heading--inner\">\n\t\t<div class=\"pxl-heading-content\">\n\t\t\t\n\t\t\t<h3 class=\"pxl-item--title clip style-default highlight-default \" data-wow-delay=\"ms\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\tPercurso Profissional\t\n\t\t\t\t\t\n\t\t\t<\/h3>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c56991c elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-pxl_border_animate\" data-id=\"c56991c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"pxl_border_animate.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-border-animate pxl-border-animate1 default\">\r\n  <div class=\"pxl-border-inner \" data-wow-delay=\"ms\"><\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e8c9d2 elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-pxl_border_animate\" data-id=\"5e8c9d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"pxl_border_animate.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-border-animate pxl-border-animate1 default\">\r\n  <div class=\"pxl-border-inner \" data-wow-delay=\"ms\"><\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t<div class=\"elementor-element elementor-element-def0dae e-con-full e-flex pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"def0dae\" data-element_type=\"container\" data-e-type=\"container\"><div class=\"elementor-element elementor-element-d5f35ec e-con-full e-flex pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"d5f35ec\" data-element_type=\"container\" data-e-type=\"container\">\t\t<div class=\"elementor-element elementor-element-a7b1d41 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"a7b1d41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner style-default wow fadeInUp\" data-wow-delay=\"700ms\">\n\t\t<p>Iniciou a sua carreira profissional no setor imobili\u00e1rio como consultor de desenvolvimento estrat\u00e9gico, supervisionando projetos desde a defini\u00e7\u00e3o conceptual inicial at\u00e9 \u00e0 comercializa\u00e7\u00e3o e execu\u00e7\u00e3o de marketing. Esta experi\u00eancia posicionou-o na intersec\u00e7\u00e3o entre a estrat\u00e9gia de desenvolvimento e o posicionamento de mercado.<br \/><br \/>Entre 1991 e 2006, foi membro do Conselho de Administra\u00e7\u00e3o da IMOLOC, parte do grupo empresarial FIPAR, onde foi respons\u00e1vel pelo desenvolvimento de projetos imobili\u00e1rios de grande escala. Durante este per\u00edodo, a empresa geria simultaneamente cerca de 300 000 m\u00b2 de projetos de constru\u00e7\u00e3o, representando cerca de 400 milh\u00f5es de euros em volume de transa\u00e7\u00f5es. Foi tamb\u00e9m pioneira na segmenta\u00e7\u00e3o do mercado imobili\u00e1rio em submarcas, introduzindo abordagens inovadoras ao desenvolvimento residencial, de escrit\u00f3rios e comercial atrav\u00e9s de conceitos de design avan\u00e7ados e aplica\u00e7\u00e3o de materiais, posteriormente analisados por universidades como um caso de estudo empresarial.<br \/><br \/>Posteriormente, fundou uma empresa de desenvolvimento residencial que introduziu estrat\u00e9gias de segmenta\u00e7\u00e3o pioneiras direcionadas a compradores solteiros e casais sem filhos, antecipando a evolu\u00e7\u00e3o dos padr\u00f5es de procura demogr\u00e1fica.<\/p><p>Como empres\u00e1rio, fundou v\u00e1rias empresas dedicadas ao desenvolvimento imobili\u00e1rio em grande escala com abordagens conceptuais diferenciadas. Entre estas iniciativas destacam-se o desenvolvimento da Quinta do Bom Sucesso, em \u00d3bidos \u2014 reconhecido como um dos resorts de design mais bem concebidos da Europa e que contou com a participa\u00e7\u00e3o de arquitetos de renome nacional e internacional \u2014, bem como os projetos Herdades de Santo Estev\u00e3o, posicionados como uma alternativa residencial ao estilo de vida lisboeta.<\/p><p>Mais tarde, fundou uma empresa de consultoria focada em investimento imobili\u00e1rio e estrat\u00e9gia de desenvolvimento, prestando orienta\u00e7\u00e3o sobre estrutura\u00e7\u00e3o de projetos e aloca\u00e7\u00e3o de capital at\u00e9 2019.<br \/>Em 2022, juntou-se \u00e0 Havos como Consultor S\u00e9nior, contribuindo com vis\u00e3o estrat\u00e9gica e experi\u00eancia em desenvolvimento para iniciativas de investimento e consultoria.<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Jorge Marques Pinto Senior Advisor Consultor s\u00e9nior em desenvolvimento imobili\u00e1rio com d\u00e9cadas de experi\u00eancia em conce\u00e7\u00e3o estrat\u00e9gica de projetos, estrutura\u00e7\u00e3o de investimentos e desenvolvimento imobili\u00e1rio em grande escala. A sua carreira abrange fun\u00e7\u00f5es de lideran\u00e7a em projetos inovadores residenciais, comerciais e tur\u00edsticos, combinando vis\u00e3o conceptual com execu\u00e7\u00e3o em v\u00e1rios ciclos de mercado. Reconhecido por criar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":10363,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-16497","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/havos.pt\/pt_pt\/wp-json\/wp\/v2\/pages\/16497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/havos.pt\/pt_pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/havos.pt\/pt_pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/havos.pt\/pt_pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/havos.pt\/pt_pt\/wp-json\/wp\/v2\/comments?post=16497"}],"version-history":[{"count":21,"href":"https:\/\/havos.pt\/pt_pt\/wp-json\/wp\/v2\/pages\/16497\/revisions"}],"predecessor-version":[{"id":17772,"href":"https:\/\/havos.pt\/pt_pt\/wp-json\/wp\/v2\/pages\/16497\/revisions\/17772"}],"up":[{"embeddable":true,"href":"https:\/\/havos.pt\/pt_pt\/wp-json\/wp\/v2\/pages\/10363"}],"wp:attachment":[{"href":"https:\/\/havos.pt\/pt_pt\/wp-json\/wp\/v2\/media?parent=16497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}