{"id":16350,"date":"2026-02-16T16:40:05","date_gmt":"2026-02-16T16:40:05","guid":{"rendered":"https:\/\/havos.pt\/?page_id=16350"},"modified":"2026-03-12T21:50:48","modified_gmt":"2026-03-12T21:50:48","slug":"luis-milagre-mesquita","status":"publish","type":"page","link":"https:\/\/havos.pt\/pt_pt\/havos\/luis-milagre-mesquita\/","title":{"rendered":"Lu\u00eds Milagre Mesquita"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"16350\" class=\"elementor elementor-16350\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a8fcdff e-flex e-con-boxed pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-parent \" data-id=\"a8fcdff\" data-element_type=\"container\" data-e-type=\"container\">\t\t\t<div class=\"e-con-inner\">\r\n\t\t<div class=\"elementor-element elementor-element-5f27534 e-con-full e-flex pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"5f27534\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\"><div class=\"elementor-element elementor-element-b61d740 e-con-full pxl-row-divider-active pxl-row-divider-divider-border-line e-flex pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"b61d740\" data-element_type=\"container\" data-e-type=\"container\"><div class=\"pxl-divider-border-line\"><div class=\"pxl-item-line pxl-border-line-top pxl-item-line-width\"><\/div><div class=\"pxl-item-line pxl-border-line-bottom pxl-item-line-width\"><\/div><div class=\"pxl-item-line pxl-border-line-left pxl-item-line-height\"><\/div><div class=\"pxl-item-line pxl-border-line-right pxl-item-line-height\"><\/div><div class=\"pxl-item-line pxl-border-line-top-left pxl-border-corner wow LineRotate\" data-wow-delay=\"300ms\"><\/div><div class=\"pxl-item-line pxl-border-line-top-right pxl-border-corner wow LineRotate\" data-wow-delay=\"300ms\"><\/div><div class=\"pxl-item-line pxl-border-line-bottom-left pxl-border-corner wow LineRotate\" data-wow-delay=\"300ms\"><\/div><div class=\"pxl-item-line pxl-border-line-bottom-right pxl-border-corner wow LineRotate\" data-wow-delay=\"300ms\"><\/div><\/div>\t\t<div class=\"elementor-element elementor-element-5c3a213 elementor-widget elementor-widget-pxl_slider\" data-id=\"5c3a213\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n    <div class=\"pxl-swiper-slider pxl-element-slider pxl-swiper-nogap style1\" >\n        <div class=\"pxl-carousel-inner\">\n            <div class=\"pxl-swiper-container\" dir=\"ltr\" data-settings=\"{&quot;slide_direction&quot;:&quot;horizontal&quot;,&quot;slide_percolumn&quot;:&quot;1&quot;,&quot;slide_mode&quot;:&quot;fade&quot;,&quot;slides_to_show&quot;:&quot;1&quot;,&quot;slides_to_show_xxl&quot;:&quot;1&quot;,&quot;slides_to_show_lg&quot;:&quot;1&quot;,&quot;slides_to_show_md&quot;:&quot;1&quot;,&quot;slides_to_show_sm&quot;:&quot;1&quot;,&quot;slides_to_show_xs&quot;:&quot;1&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;arrow&quot;:false,&quot;pagination&quot;:false,&quot;pagination_type&quot;:&quot;bullets&quot;,&quot;autoplay&quot;:false,&quot;pause_on_hover&quot;:false,&quot;pause_on_interaction&quot;:true,&quot;delay&quot;:5000,&quot;loop&quot;:false,&quot;speed&quot;:500}\">\n                <div class=\"pxl-swiper-wrapper\">\n                                                <div class=\"pxl-swiper-slide\">\n                                <div class=\"pxl-slider--inner elementor-repeater-item-2a9a549\">\n                                                                        <div class=\"pxl-slider--content\">\n                                        \t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"16355\" class=\"elementor elementor-16355\" data-elementor-post-type=\"pxl-template\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4061eaa e-con-full e-flex pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-parent \" data-id=\"4061eaa\" data-element_type=\"container\" data-e-type=\"container\"><div class=\"elementor-element elementor-element-88babba e-con-full e-flex pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"88babba\" data-element_type=\"container\" data-e-type=\"container\">\t\t<div class=\"elementor-element elementor-element-37f7048 elementor-widget elementor-widget-pxl_heading\" data-id=\"37f7048\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div id=\"pxl-pxl_heading-37f7048-6479\" class=\"pxl-heading px-sub-title-default-style \">\n\t<div class=\"pxl-heading--inner\">\n\t\t<div class=\"pxl-heading-content\">\n\t\t\t\n\t\t\t<h1 class=\"pxl-item--title clip style-default highlight-default \" data-wow-delay=\"ms\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\tLu\u00eds Milagre Mesquita\t\n\t\t\t\t\t\n\t\t\t<\/h1>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e104929 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"e104929\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner style-default \" data-wow-delay=\"ms\">\n\t\tPartner | Head of Capital Markets\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-626cf51 elementor-widget elementor-widget-pxl_icon\" data-id=\"626cf51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"pxl-icon-list pxl-icon1 wow zoomInSmall icon-style2\" data-wow-delay=\"500ms\">\r\n                                    <a class=\"elementor-repeater-item-fd8ab11 pxl-mr-22\" href=\"https:\/\/www.linkedin.com\/in\/luismesquita\/\" target=\"_blank\">\r\n                    <i aria-hidden=\"true\" class=\"fab fa-linkedin-in\"><\/i>                <\/a>\r\n                        <\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t<div class=\"elementor-element elementor-element-db5b659 e-con-full e-flex pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"db5b659\" data-element_type=\"container\" data-e-type=\"container\">\t\t<div class=\"elementor-element elementor-element-ce0bfaa elementor-widget elementor-widget-pxl_banner_box\" data-id=\"ce0bfaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_banner_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-banner-box pxl-banner-box2\">\r\n    <div class=\"pxl-banner-inner\">\r\n        <div class=\"pxl-item-left\">\r\n                                            <\/div>\r\n                    <div class=\"pxl-item--img wow zoomInSmall\" data-wow-delay=\"500ms\">\r\n                <div class=\"pxl-image\">\r\n                    <img fetchpriority=\"high\" decoding=\"async\" class=\"\" src=\"https:\/\/havos.pt\/wp-content\/uploads\/2026\/02\/Luis-Milagre-Mesquita-Havos-490x490.png\" width=\"490\" height=\"490\" alt=\"Homem de fato azul, posando em frente a escadas, num ambiente claro e moderno.\" title=\"Luis Milagre Mesquita - Havos\" \/>                <\/div>\r\n            <\/div>\r\n                <div class=\"pxl-item-right\">\r\n                                            <\/div>\r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t<div class=\"elementor-element elementor-element-bcb8d8d e-con-full e-flex pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"bcb8d8d\" data-element_type=\"container\" data-e-type=\"container\">\t\t<div class=\"elementor-element elementor-element-df19716 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"df19716\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner style-default wow fadeInUp\" data-wow-delay=\"700ms\">\n\t\t<p>Executivo com experi\u00eancia consolidada em Corporate Real Estate e mercados de capital, combinando vis\u00e3o estrat\u00e9gica com forte capacidade de execu\u00e7\u00e3o em contextos orientados para investimento.<br \/>Apresenta percurso comprovado em asset e fund management, cria\u00e7\u00e3o de valor, reposicionamento de ativos e estrutura\u00e7\u00e3o de transa\u00e7\u00f5es nos segmentos de escrit\u00f3rios, retalho e projetos de uso misto.<br \/>Destaca-se pela capacidade de originar oportunidades, estruturar opera\u00e7\u00f5es e liderar equipas multidisciplinares, integrando perspetivas financeiras, operacionais e de mercado na tomada de decis\u00e3o.<br \/><br \/>Reconhecido por um estilo de lideran\u00e7a pragm\u00e1tico, orientado para resultados e alinhado com objetivos estrat\u00e9gicos de longo prazo.<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-114ade7 e-con-full e-flex pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"114ade7\" data-element_type=\"container\" data-e-type=\"container\">\t\t<div class=\"elementor-element elementor-element-4b4ddf9 elementor-widget elementor-widget-pxl_button_custom\" data-id=\"4b4ddf9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_button_custom.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-button-custom pxl-button-custom1 style2\">\r\n    <div class=\"pxl-item--inner pxl-atc-onepage \" data-wow-delay=\"ms\">\r\n        <a class=\"btn-cutom btn\" href=\"#section-team-details\" data-onepage-offset=\"100\">                                        <span class=\"pxl-icon-arrow\">\r\n                    <svg width=\"14\" height=\"7\" viewBox=\"0 0 14 7\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\r\n                      <path d=\"M13 1.5L7 5.5L1 1.5\" stroke=\"white\" stroke-width=\"1.5\" stroke-linejoin=\"round\"\/>\r\n                    <\/svg>\r\n                    <svg width=\"14\" height=\"7\" viewBox=\"0 0 14 7\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\r\n                      <path d=\"M13 1.5L7 5.5L1 1.5\" stroke=\"white\" stroke-width=\"1.5\" stroke-linejoin=\"round\"\/>\r\n                    <\/svg>\r\n                <\/span>\r\n                <span class=\"pxl-btn-title\">Deslize para explorar<\/span>\r\n                    <\/a>    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t                                    <\/div>\n                               <\/div>\n                            <\/div>\n                                                            <\/div>\n            <\/div>\n        <\/div>\n\n        \n        \n    <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t<div class=\"elementor-element elementor-element-78be849 e-flex e-con-boxed pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-parent \" data-id=\"78be849\" data-element_type=\"container\" data-e-type=\"container\">\t\t\t<div class=\"e-con-inner\">\r\n\t\t<div class=\"elementor-element elementor-element-b04bebe e-con-full e-flex pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"b04bebe\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\"><div class=\"elementor-element elementor-element-42996e2 e-con-full pxl-row-scroll-fixed e-flex pxl-column-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"42996e2\" data-element_type=\"container\" data-e-type=\"container\"><div class=\"elementor-element elementor-element-b2bfa4b e-con-full pxl-column-sticky e-flex pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"b2bfa4b\" data-element_type=\"container\" data-e-type=\"container\">\t\t<div class=\"elementor-element elementor-element-e64c60f elementor-widget elementor-widget-pxl_heading\" data-id=\"e64c60f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div id=\"pxl-pxl_heading-e64c60f-1589\" class=\"pxl-heading px-sub-title-default-style \">\n\t<div class=\"pxl-heading--inner\">\n\t\t<div class=\"pxl-heading-content\">\n\t\t\t\n\t\t\t<h3 class=\"pxl-item--title clip style-default highlight-default \" data-wow-delay=\"ms\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\tCompet\u00eancias Principais\t\n\t\t\t\t\t\n\t\t\t<\/h3>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5354d6 elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-pxl_border_animate\" data-id=\"a5354d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"pxl_border_animate.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-border-animate pxl-border-animate1 default\">\r\n  <div class=\"pxl-border-inner \" data-wow-delay=\"ms\"><\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db91a14 elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-pxl_border_animate\" data-id=\"db91a14\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"pxl_border_animate.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-border-animate pxl-border-animate1 default\">\r\n  <div class=\"pxl-border-inner \" data-wow-delay=\"ms\"><\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t<div class=\"elementor-element elementor-element-47a7ed9 e-con-full e-flex pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"47a7ed9\" data-element_type=\"container\" data-e-type=\"container\"><div class=\"elementor-element elementor-element-3080f37 e-con-full e-flex pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"3080f37\" data-element_type=\"container\" data-e-type=\"container\">\t\t<div class=\"elementor-element elementor-element-1a2726d elementor-widget elementor-widget-pxl_text_editor\" data-id=\"1a2726d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner style-default \" data-wow-delay=\"ms\">\n\t\t1. Mercados de Capitais\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97c10f9 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"97c10f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner style-default \" data-wow-delay=\"ms\">\n\t\t2. Corporate Real Estate\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff4b0cf elementor-widget elementor-widget-pxl_text_editor\" data-id=\"ff4b0cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner style-default \" data-wow-delay=\"ms\">\n\t\t3. Assessoria em Investimento e Transa\u00e7\u00f5es\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ea5be7 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"2ea5be7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner style-default \" data-wow-delay=\"ms\">\n\t\t4. Asset &#038; Fund Management\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1cc3c2 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"c1cc3c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner style-default \" data-wow-delay=\"ms\">\n\t\t5. Vendas e Desenvolvimento de Neg\u00f3cio\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a8b468 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"4a8b468\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner style-default \" data-wow-delay=\"ms\">\n\t\t<p>6. Gest\u00e3o de equipas<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t<div class=\"elementor-element elementor-element-d462fcb e-flex e-con-boxed pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-parent \" data-id=\"d462fcb\" data-element_type=\"container\" data-e-type=\"container\">\t\t\t<div class=\"e-con-inner\">\r\n\t\t<div class=\"elementor-element elementor-element-0211a18 e-con-full e-flex pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"0211a18\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\"><div class=\"elementor-element elementor-element-cd06df5 e-con-full pxl-row-scroll-fixed e-flex pxl-column-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"cd06df5\" data-element_type=\"container\" data-e-type=\"container\"><div class=\"elementor-element elementor-element-6738604 e-con-full pxl-column-sticky e-flex pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"6738604\" data-element_type=\"container\" data-e-type=\"container\">\t\t<div class=\"elementor-element elementor-element-5964547 elementor-widget elementor-widget-pxl_heading\" data-id=\"5964547\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div id=\"pxl-pxl_heading-5964547-5855\" class=\"pxl-heading px-sub-title-default-style \">\n\t<div class=\"pxl-heading--inner\">\n\t\t<div class=\"pxl-heading-content\">\n\t\t\t\n\t\t\t<h3 class=\"pxl-item--title clip style-default highlight-default \" data-wow-delay=\"ms\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\tPercurso Profissional\t\n\t\t\t\t\t\n\t\t\t<\/h3>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1175adf elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-pxl_border_animate\" data-id=\"1175adf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"pxl_border_animate.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-border-animate pxl-border-animate1 default\">\r\n  <div class=\"pxl-border-inner \" data-wow-delay=\"ms\"><\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60df98f elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-pxl_border_animate\" data-id=\"60df98f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"pxl_border_animate.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-border-animate pxl-border-animate1 default\">\r\n  <div class=\"pxl-border-inner \" data-wow-delay=\"ms\"><\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t<div class=\"elementor-element elementor-element-6f11c57 e-con-full e-flex pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"6f11c57\" data-element_type=\"container\" data-e-type=\"container\"><div class=\"elementor-element elementor-element-32c0911 e-con-full e-flex pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child \" data-id=\"32c0911\" data-element_type=\"container\" data-e-type=\"container\">\t\t<div class=\"elementor-element elementor-element-34f0a24 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"34f0a24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner style-default wow fadeInUp\" data-wow-delay=\"700ms\">\n\t\t<p><span style=\"font-weight: 400\">Lu\u00eds Mesquita \u00e9 um executivo de Corporate Real Estate com mais de tr\u00eas d\u00e9cadas de experi\u00eancia em investimento imobili\u00e1rio, mercados de capital, gest\u00e3o de ativos e fundos, bem como desenvolvimento de neg\u00f3cio, adquirida em plataformas nacionais e multinacionais.<br \/><br \/><\/span><span style=\"font-weight: 400\">Iniciou a sua carreira no desenvolvimento de neg\u00f3cios de retalho, tendo fundado e expandido diversos conceitos comerciais em Portugal, implementando com sucesso estrat\u00e9gias de franchising e expans\u00e3o.<br \/><br \/><\/span><span style=\"font-weight: 400\">Posteriormente integrou a FNAC, onde desempenhou fun\u00e7\u00f5es de dire\u00e7\u00e3o, liderando processos de reestrutura\u00e7\u00e3o da rede, otimiza\u00e7\u00e3o operacional e crescimento de receitas.<br \/><br \/><\/span><span style=\"font-weight: 400\">Transitou depois para a \u00e1rea de investimento imobili\u00e1rio e asset management na Imorendimento, onde geriu portf\u00f3lios nacionais de retalho e assumiu posteriormente a responsabilidade pela gest\u00e3o de ativos de um fundo imobili\u00e1rio, supervisionando a estrat\u00e9gia de comercializa\u00e7\u00e3o, reposicionamento e cria\u00e7\u00e3o de valor.<br \/><br \/><\/span><span style=\"font-weight: 400\">Enquanto consultor estrat\u00e9gico, teve um papel determinante no desenvolvimento do Lionesa Business Hub, contribuindo para o master plan, estrat\u00e9gia comercial e defini\u00e7\u00e3o do tenant mix, ajudando a afirmar o projeto como um dos principais parques empresariais em Portugal.<br \/><br \/><\/span><span style=\"font-weight: 400\">Em 2017, fundou e liderou o escrit\u00f3rio da CBRE no Porto, reportando diretamente ao Managing Director em Portugal. Sob a sua lideran\u00e7a, o escrit\u00f3rio superou consistentemente os objetivos definidos e executou transa\u00e7\u00f5es superiores a 200 milh\u00f5es de euros nas \u00e1reas de Capital Markets e Advisory &amp; Transactions.<br \/><br \/><\/span><span style=\"font-weight: 400\">Atualmente \u00e9 Partner da Havos Real Estate, onde lidera a \u00e1rea de Capital Markets e participa ativamente na defini\u00e7\u00e3o estrat\u00e9gica e governa\u00e7\u00e3o executiva da sociedade.<\/span><\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Lu\u00eds Milagre Mesquita Partner | Head of Capital Markets Executivo com uma s\u00f3lida combina\u00e7\u00e3o de vis\u00e3o estrat\u00e9gica e capacidade de execu\u00e7\u00e3o nas \u00e1reas de Corporate Real Estate, mercados de capital e contextos orientados para investimento. Apresenta experi\u00eancia comprovada em asset e fund management, cria\u00e7\u00e3o de valor, reposicionamento de ativos e execu\u00e7\u00e3o de transa\u00e7\u00f5es nos segmentos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":10363,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-16350","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/havos.pt\/pt_pt\/wp-json\/wp\/v2\/pages\/16350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/havos.pt\/pt_pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/havos.pt\/pt_pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/havos.pt\/pt_pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/havos.pt\/pt_pt\/wp-json\/wp\/v2\/comments?post=16350"}],"version-history":[{"count":26,"href":"https:\/\/havos.pt\/pt_pt\/wp-json\/wp\/v2\/pages\/16350\/revisions"}],"predecessor-version":[{"id":17773,"href":"https:\/\/havos.pt\/pt_pt\/wp-json\/wp\/v2\/pages\/16350\/revisions\/17773"}],"up":[{"embeddable":true,"href":"https:\/\/havos.pt\/pt_pt\/wp-json\/wp\/v2\/pages\/10363"}],"wp:attachment":[{"href":"https:\/\/havos.pt\/pt_pt\/wp-json\/wp\/v2\/media?parent=16350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}